{"id":54282,"date":"2019-04-02T11:41:25","date_gmt":"2019-04-02T09:41:25","guid":{"rendered":"https:\/\/marieclaire.be\/nl\/?p=54282"},"modified":"2019-04-02T11:42:57","modified_gmt":"2019-04-02T09:42:57","slug":"5-opkomende-rommelmarkten-belgie","status":"publish","type":"post","link":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/","title":{"rendered":"Agenda: 4 gezellige rommelmarkten die je de komende zomermaanden niet wil missen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"Nu de lente is ingezet, gaat ook het seizoen van de rommelmarkten van start. ...","protected":false},"author":7,"featured_media":54433,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30,25],"tags":[6555,6554,75,1533],"class_list":["post-54282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hotspots","category-lifestyle-cultuur","tag-brocanterie","tag-rommelmarkt","tag-shopping","tag-vintage"],"acf":[],"_yoast_wpseo_metadesc":"Het seizoen van de rommelmarkten gaat van start! Ontdek welke leuke opkomende rommelmarkten jij binnenkort zal kunnen verkennen!","image_verticale":null,"_yoast_wpseo_title":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agenda: 4 gezellige rommelmarkten die je de komende zomermaanden niet wil missen - Marie Claire<\/title>\n<meta name=\"description\" content=\"Het seizoen van de rommelmarkten gaat van start! Ontdek welke leuke opkomende rommelmarkten jij binnenkort zal kunnen verkennen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/\" \/>\n<link rel=\"next\" href=\"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenda: 4 gezellige rommelmarkten die je de komende zomermaanden niet wil missen - Marie Claire\" \/>\n<meta property=\"og:description\" content=\"Het seizoen van de rommelmarkten gaat van start! Ontdek welke leuke opkomende rommelmarkten jij binnenkort zal kunnen verkennen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/\" \/>\n<meta property=\"og:site_name\" content=\"Marie Claire\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarieClaireBelgie\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-02T09:41:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-02T09:42:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2019\/04\/rommelmarkten_belgie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1050\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MarieClaire Belg\u00efe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MarieClaireBelg\" \/>\n<meta name=\"twitter:site\" content=\"@MarieClaireBelg\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"MarieClaire Belg\u00efe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/5-opkomende-rommelmarkten-belgie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/5-opkomende-rommelmarkten-belgie\\\/\"},\"author\":{\"name\":\"MarieClaire Belg\u00efe\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#\\\/schema\\\/person\\\/40ecaf04184069a7d983c6441f961736\"},\"headline\":\"Agenda: 4 gezellige rommelmarkten die je de komende zomermaanden niet wil missen\",\"datePublished\":\"2019-04-02T09:41:25+00:00\",\"dateModified\":\"2019-04-02T09:42:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/5-opkomende-rommelmarkten-belgie\\\/\"},\"wordCount\":413,\"publisher\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/5-opkomende-rommelmarkten-belgie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/rommelmarkten_belgie.jpg\",\"keywords\":[\"brocanterie\",\"rommelmarkt\",\"Shopping\",\"vintage\"],\"articleSection\":[\"Hotspots\",\"Lifestyle &amp; cultuur\"],\"inLanguage\":\"nl-BE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/5-opkomende-rommelmarkten-belgie\\\/\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/5-opkomende-rommelmarkten-belgie\\\/\",\"name\":\"Agenda: 4 gezellige rommelmarkten die je de komende zomermaanden niet wil missen - Marie Claire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/5-opkomende-rommelmarkten-belgie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/5-opkomende-rommelmarkten-belgie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/rommelmarkten_belgie.jpg\",\"datePublished\":\"2019-04-02T09:41:25+00:00\",\"dateModified\":\"2019-04-02T09:42:57+00:00\",\"description\":\"Het seizoen van de rommelmarkten gaat van start! Ontdek welke leuke opkomende rommelmarkten jij binnenkort zal kunnen verkennen!\",\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marieclaire.be\\\/nl\\\/5-opkomende-rommelmarkten-belgie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/5-opkomende-rommelmarkten-belgie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/rommelmarkten_belgie.jpg\",\"contentUrl\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/rommelmarkten_belgie.jpg\",\"width\":1050,\"height\":550,\"caption\":\"Unsplash & Pexels\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/\",\"name\":\"Marie Claire Belgie\",\"description\":\"Marie Claire Belgie, de site voor de intelligente vrouw vol mode, beauty, lifestyle, hotspots en nieuwtjes. Think smart - look amazing.\",\"publisher\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#organization\",\"name\":\"Marie Claire\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/marieclaire-512.png\",\"contentUrl\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/marieclaire-512.png\",\"width\":512,\"height\":512,\"caption\":\"Marie Claire\"},\"image\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MarieClaireBelgie\\\/\",\"https:\\\/\\\/x.com\\\/MarieClaireBelg\",\"https:\\\/\\\/www.instagram.com\\\/marieclaire_belgie\\\/\",\"https:\\\/\\\/fr.pinterest.com\\\/marieclairebe\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#\\\/schema\\\/person\\\/40ecaf04184069a7d983c6441f961736\",\"name\":\"MarieClaire Belg\u00efe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/14156610_872896619478535_590200538_a-96x96.jpg\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/14156610_872896619478535_590200538_a-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/14156610_872896619478535_590200538_a-96x96.jpg\",\"caption\":\"MarieClaire Belg\u00efe\"},\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/author\\\/marie-claire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agenda: 4 gezellige rommelmarkten die je de komende zomermaanden niet wil missen - Marie Claire","description":"Het seizoen van de rommelmarkten gaat van start! Ontdek welke leuke opkomende rommelmarkten jij binnenkort zal kunnen verkennen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/","next":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/2\/","og_locale":"nl_BE","og_type":"article","og_title":"Agenda: 4 gezellige rommelmarkten die je de komende zomermaanden niet wil missen - Marie Claire","og_description":"Het seizoen van de rommelmarkten gaat van start! Ontdek welke leuke opkomende rommelmarkten jij binnenkort zal kunnen verkennen!","og_url":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/","og_site_name":"Marie Claire","article_publisher":"https:\/\/www.facebook.com\/MarieClaireBelgie\/","article_published_time":"2019-04-02T09:41:25+00:00","article_modified_time":"2019-04-02T09:42:57+00:00","og_image":[{"width":1050,"height":550,"url":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2019\/04\/rommelmarkten_belgie.jpg","type":"image\/jpeg"}],"author":"MarieClaire Belg\u00efe","twitter_card":"summary_large_image","twitter_creator":"@MarieClaireBelg","twitter_site":"@MarieClaireBelg","twitter_misc":{"Geschreven door":"MarieClaire Belg\u00efe","Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/#article","isPartOf":{"@id":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/"},"author":{"name":"MarieClaire Belg\u00efe","@id":"https:\/\/marieclaire.be\/nl\/#\/schema\/person\/40ecaf04184069a7d983c6441f961736"},"headline":"Agenda: 4 gezellige rommelmarkten die je de komende zomermaanden niet wil missen","datePublished":"2019-04-02T09:41:25+00:00","dateModified":"2019-04-02T09:42:57+00:00","mainEntityOfPage":{"@id":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/"},"wordCount":413,"publisher":{"@id":"https:\/\/marieclaire.be\/nl\/#organization"},"image":{"@id":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/#primaryimage"},"thumbnailUrl":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2019\/04\/rommelmarkten_belgie.jpg","keywords":["brocanterie","rommelmarkt","Shopping","vintage"],"articleSection":["Hotspots","Lifestyle &amp; cultuur"],"inLanguage":"nl-BE"},{"@type":"WebPage","@id":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/","url":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/","name":"Agenda: 4 gezellige rommelmarkten die je de komende zomermaanden niet wil missen - Marie Claire","isPartOf":{"@id":"https:\/\/marieclaire.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/#primaryimage"},"image":{"@id":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/#primaryimage"},"thumbnailUrl":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2019\/04\/rommelmarkten_belgie.jpg","datePublished":"2019-04-02T09:41:25+00:00","dateModified":"2019-04-02T09:42:57+00:00","description":"Het seizoen van de rommelmarkten gaat van start! Ontdek welke leuke opkomende rommelmarkten jij binnenkort zal kunnen verkennen!","inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/"]}]},{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/marieclaire.be\/nl\/5-opkomende-rommelmarkten-belgie\/#primaryimage","url":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2019\/04\/rommelmarkten_belgie.jpg","contentUrl":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2019\/04\/rommelmarkten_belgie.jpg","width":1050,"height":550,"caption":"Unsplash & Pexels"},{"@type":"WebSite","@id":"https:\/\/marieclaire.be\/nl\/#website","url":"https:\/\/marieclaire.be\/nl\/","name":"Marie Claire Belgie","description":"Marie Claire Belgie, de site voor de intelligente vrouw vol mode, beauty, lifestyle, hotspots en nieuwtjes. Think smart - look amazing.","publisher":{"@id":"https:\/\/marieclaire.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marieclaire.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Organization","@id":"https:\/\/marieclaire.be\/nl\/#organization","name":"Marie Claire","url":"https:\/\/marieclaire.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/marieclaire.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2024\/12\/marieclaire-512.png","contentUrl":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2024\/12\/marieclaire-512.png","width":512,"height":512,"caption":"Marie Claire"},"image":{"@id":"https:\/\/marieclaire.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarieClaireBelgie\/","https:\/\/x.com\/MarieClaireBelg","https:\/\/www.instagram.com\/marieclaire_belgie\/","https:\/\/fr.pinterest.com\/marieclairebe\/"]},{"@type":"Person","@id":"https:\/\/marieclaire.be\/nl\/#\/schema\/person\/40ecaf04184069a7d983c6441f961736","name":"MarieClaire Belg\u00efe","image":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2017\/05\/14156610_872896619478535_590200538_a-96x96.jpg","url":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2017\/05\/14156610_872896619478535_590200538_a-96x96.jpg","contentUrl":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2017\/05\/14156610_872896619478535_590200538_a-96x96.jpg","caption":"MarieClaire Belg\u00efe"},"url":"https:\/\/marieclaire.be\/nl\/author\/marie-claire\/"}]}},"_links":{"self":[{"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/posts\/54282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/comments?post=54282"}],"version-history":[{"count":8,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/posts\/54282\/revisions"}],"predecessor-version":[{"id":54434,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/posts\/54282\/revisions\/54434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/media\/54433"}],"wp:attachment":[{"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/media?parent=54282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/categories?post=54282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/tags?post=54282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}