{"id":124991,"date":"2023-11-10T14:31:57","date_gmt":"2023-11-10T13:31:57","guid":{"rendered":"https:\/\/marieclaire.be\/nl\/?p=124991"},"modified":"2023-12-06T08:03:20","modified_gmt":"2023-12-06T07:03:20","slug":"uitgetest-een-laserbehandeling-tegen-couperose","status":"publish","type":"post","link":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/","title":{"rendered":"Uitgetest: een laserbehandeling tegen couperose"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"In tegenstelling tot wat Hollywood ons wil doen geloven, bestaat een perfect gladde en egale teint niet. ...","protected":false},"author":58,"featured_media":125000,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7,19],"tags":[],"class_list":["post-124991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beauty-marie-claire","category-getest"],"acf":[],"_yoast_wpseo_metadesc":"Een behandeling met laser zou erg doeltreffend zijn tegen couperose. Klopt dat ook? Wij probeerden het uit.","image_verticale":"125001","_yoast_wpseo_title":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uitgetest: een laserbehandeling tegen couperose - Marie Claire<\/title>\n<meta name=\"description\" content=\"Een behandeling met laser zou erg doeltreffend zijn tegen couperose. Klopt dat ook? Wij probeerden het uit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/\" \/>\n<link rel=\"next\" href=\"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uitgetest: een laserbehandeling tegen couperose - Marie Claire\" \/>\n<meta property=\"og:description\" content=\"Een behandeling met laser zou erg doeltreffend zijn tegen couperose. Klopt dat ook? Wij probeerden het uit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/\" \/>\n<meta property=\"og:site_name\" content=\"Marie Claire\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarieClaireBelgie\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-10T13:31:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T07:03:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2023\/11\/uitgelicht-1280px-op-670px-20.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Timon Van Mechelen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MarieClaireBelg\" \/>\n<meta name=\"twitter:site\" content=\"@MarieClaireBelg\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Timon Van Mechelen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/uitgetest-een-laserbehandeling-tegen-couperose\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/uitgetest-een-laserbehandeling-tegen-couperose\\\/\"},\"author\":{\"name\":\"Timon Van Mechelen\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#\\\/schema\\\/person\\\/a1f685e615c2c2c6e4458ebdce4c3a9e\"},\"headline\":\"Uitgetest: een laserbehandeling tegen couperose\",\"datePublished\":\"2023-11-10T13:31:57+00:00\",\"dateModified\":\"2023-12-06T07:03:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/uitgetest-een-laserbehandeling-tegen-couperose\\\/\"},\"wordCount\":657,\"publisher\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/uitgetest-een-laserbehandeling-tegen-couperose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/uitgelicht-1280px-op-670px-20.png\",\"articleSection\":[\"Beauty\",\"Het beauty verdict\"],\"inLanguage\":\"nl-BE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/uitgetest-een-laserbehandeling-tegen-couperose\\\/\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/uitgetest-een-laserbehandeling-tegen-couperose\\\/\",\"name\":\"Uitgetest: een laserbehandeling tegen couperose - Marie Claire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/uitgetest-een-laserbehandeling-tegen-couperose\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/uitgetest-een-laserbehandeling-tegen-couperose\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/uitgelicht-1280px-op-670px-20.png\",\"datePublished\":\"2023-11-10T13:31:57+00:00\",\"dateModified\":\"2023-12-06T07:03:20+00:00\",\"description\":\"Een behandeling met laser zou erg doeltreffend zijn tegen couperose. Klopt dat ook? Wij probeerden het uit.\",\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marieclaire.be\\\/nl\\\/uitgetest-een-laserbehandeling-tegen-couperose\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/uitgetest-een-laserbehandeling-tegen-couperose\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/uitgelicht-1280px-op-670px-20.png\",\"contentUrl\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/uitgelicht-1280px-op-670px-20.png\",\"width\":1280,\"height\":670,\"caption\":\"Getty Images\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/\",\"name\":\"Marie Claire Belgie\",\"description\":\"Marie Claire Belgie, de site voor de intelligente vrouw vol mode, beauty, lifestyle, hotspots en nieuwtjes. Think smart - look amazing.\",\"publisher\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#organization\",\"name\":\"Marie Claire\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/marieclaire-512.png\",\"contentUrl\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/marieclaire-512.png\",\"width\":512,\"height\":512,\"caption\":\"Marie Claire\"},\"image\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MarieClaireBelgie\\\/\",\"https:\\\/\\\/x.com\\\/MarieClaireBelg\",\"https:\\\/\\\/www.instagram.com\\\/marieclaire_belgie\\\/\",\"https:\\\/\\\/fr.pinterest.com\\\/marieclairebe\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/#\\\/schema\\\/person\\\/a1f685e615c2c2c6e4458ebdce4c3a9e\",\"name\":\"Timon Van Mechelen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/timon-96x96.jpg\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/timon-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/timon-96x96.jpg\",\"caption\":\"Timon Van Mechelen\"},\"description\":\"Als mode-expert weet hij trends en ontwikkelingen als geen ander te duiden. Is weg van Dries Van Noten en Prada en ziet zijn kleren als waardevolle investeringen. Haalt evenveel plezier uit de stockverkopen als jij uit je verjaardag, kerst en zomervakantie samen. Vindt verder weinig bevredigender dan te veel natuurwijn drinken en mensen kijken op een terras.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/timonvm\\\/\"],\"url\":\"https:\\\/\\\/marieclaire.be\\\/nl\\\/author\\\/timon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uitgetest: een laserbehandeling tegen couperose - Marie Claire","description":"Een behandeling met laser zou erg doeltreffend zijn tegen couperose. Klopt dat ook? Wij probeerden het uit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/","next":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/2\/","og_locale":"nl_BE","og_type":"article","og_title":"Uitgetest: een laserbehandeling tegen couperose - Marie Claire","og_description":"Een behandeling met laser zou erg doeltreffend zijn tegen couperose. Klopt dat ook? Wij probeerden het uit.","og_url":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/","og_site_name":"Marie Claire","article_publisher":"https:\/\/www.facebook.com\/MarieClaireBelgie\/","article_published_time":"2023-11-10T13:31:57+00:00","article_modified_time":"2023-12-06T07:03:20+00:00","og_image":[{"width":1280,"height":670,"url":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2023\/11\/uitgelicht-1280px-op-670px-20.png","type":"image\/png"}],"author":"Timon Van Mechelen","twitter_card":"summary_large_image","twitter_creator":"@MarieClaireBelg","twitter_site":"@MarieClaireBelg","twitter_misc":{"Geschreven door":"Timon Van Mechelen","Geschatte leestijd":"4 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/#article","isPartOf":{"@id":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/"},"author":{"name":"Timon Van Mechelen","@id":"https:\/\/marieclaire.be\/nl\/#\/schema\/person\/a1f685e615c2c2c6e4458ebdce4c3a9e"},"headline":"Uitgetest: een laserbehandeling tegen couperose","datePublished":"2023-11-10T13:31:57+00:00","dateModified":"2023-12-06T07:03:20+00:00","mainEntityOfPage":{"@id":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/"},"wordCount":657,"publisher":{"@id":"https:\/\/marieclaire.be\/nl\/#organization"},"image":{"@id":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/#primaryimage"},"thumbnailUrl":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2023\/11\/uitgelicht-1280px-op-670px-20.png","articleSection":["Beauty","Het beauty verdict"],"inLanguage":"nl-BE"},{"@type":"WebPage","@id":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/","url":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/","name":"Uitgetest: een laserbehandeling tegen couperose - Marie Claire","isPartOf":{"@id":"https:\/\/marieclaire.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/#primaryimage"},"image":{"@id":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/#primaryimage"},"thumbnailUrl":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2023\/11\/uitgelicht-1280px-op-670px-20.png","datePublished":"2023-11-10T13:31:57+00:00","dateModified":"2023-12-06T07:03:20+00:00","description":"Een behandeling met laser zou erg doeltreffend zijn tegen couperose. Klopt dat ook? Wij probeerden het uit.","inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/"]}]},{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/marieclaire.be\/nl\/uitgetest-een-laserbehandeling-tegen-couperose\/#primaryimage","url":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2023\/11\/uitgelicht-1280px-op-670px-20.png","contentUrl":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2023\/11\/uitgelicht-1280px-op-670px-20.png","width":1280,"height":670,"caption":"Getty Images"},{"@type":"WebSite","@id":"https:\/\/marieclaire.be\/nl\/#website","url":"https:\/\/marieclaire.be\/nl\/","name":"Marie Claire Belgie","description":"Marie Claire Belgie, de site voor de intelligente vrouw vol mode, beauty, lifestyle, hotspots en nieuwtjes. Think smart - look amazing.","publisher":{"@id":"https:\/\/marieclaire.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marieclaire.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Organization","@id":"https:\/\/marieclaire.be\/nl\/#organization","name":"Marie Claire","url":"https:\/\/marieclaire.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/marieclaire.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2024\/12\/marieclaire-512.png","contentUrl":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2024\/12\/marieclaire-512.png","width":512,"height":512,"caption":"Marie Claire"},"image":{"@id":"https:\/\/marieclaire.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarieClaireBelgie\/","https:\/\/x.com\/MarieClaireBelg","https:\/\/www.instagram.com\/marieclaire_belgie\/","https:\/\/fr.pinterest.com\/marieclairebe\/"]},{"@type":"Person","@id":"https:\/\/marieclaire.be\/nl\/#\/schema\/person\/a1f685e615c2c2c6e4458ebdce4c3a9e","name":"Timon Van Mechelen","image":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2020\/08\/timon-96x96.jpg","url":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2020\/08\/timon-96x96.jpg","contentUrl":"https:\/\/marieclaire.be\/nl\/wp-content\/uploads\/2020\/08\/timon-96x96.jpg","caption":"Timon Van Mechelen"},"description":"Als mode-expert weet hij trends en ontwikkelingen als geen ander te duiden. Is weg van Dries Van Noten en Prada en ziet zijn kleren als waardevolle investeringen. Haalt evenveel plezier uit de stockverkopen als jij uit je verjaardag, kerst en zomervakantie samen. Vindt verder weinig bevredigender dan te veel natuurwijn drinken en mensen kijken op een terras.","sameAs":["https:\/\/www.instagram.com\/timonvm\/"],"url":"https:\/\/marieclaire.be\/nl\/author\/timon\/"}]}},"_links":{"self":[{"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/posts\/124991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/comments?post=124991"}],"version-history":[{"count":10,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/posts\/124991\/revisions"}],"predecessor-version":[{"id":126733,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/posts\/124991\/revisions\/126733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/media\/125000"}],"wp:attachment":[{"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/media?parent=124991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/categories?post=124991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marieclaire.be\/nl\/wp-json\/wp\/v2\/tags?post=124991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}