{"id":121537,"date":"2022-12-13T11:31:59","date_gmt":"2022-12-13T10:31:59","guid":{"rendered":"https:\/\/marieclaire.be\/fr\/?p=121537"},"modified":"2022-12-13T11:31:59","modified_gmt":"2022-12-13T10:31:59","slug":"recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines","status":"publish","type":"post","link":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/","title":{"rendered":"Recettes : Mocktail Basilic &#038; Fleurs de sureau avec sabl\u00e9 breton et sorbet de cl\u00e9mentines"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"Si vous avez d\u00e9cid\u00e9 de faire rimer f\u00eates de fin d&#8217;ann\u00e9e avec sobri\u00e9t\u00e9, voici une d\u00e9licieuse recette de dessert qui s&#8217;accordera \u00e0 merveille avec votre mocktail pr\u00e9f\u00e9r\u00e9.","protected":false},"author":30,"featured_media":121539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[67,70],"tags":[202],"class_list":["post-121537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lifestyle","category-recettes","tag-food"],"acf":[],"_yoast_wpseo_title":null,"_yoast_wpseo_metadesc":"Envie de faire rimer f\u00eates de fin d'ann\u00e9e avec sobri\u00e9t\u00e9 ? Voici une d\u00e9licieuse recette de dessert qui s'accordera \u00e0 merveille avec votre mocktail pr\u00e9f\u00e9r\u00e9.","image_verticale":"121538","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recettes : Mocktail Basilic &amp; Fleurs de sureau avec sabl\u00e9 breton et sorbet de cl\u00e9mentines - Marie Claire Belgique<\/title>\n<meta name=\"description\" content=\"Envie de faire rimer f\u00eates de fin d&#039;ann\u00e9e avec sobri\u00e9t\u00e9 ? Voici une d\u00e9licieuse recette de dessert qui s&#039;accordera \u00e0 merveille avec votre mocktail pr\u00e9f\u00e9r\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/\" \/>\n<link rel=\"next\" href=\"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recettes : Mocktail Basilic &amp; Fleurs de sureau avec sabl\u00e9 breton et sorbet de cl\u00e9mentines - Marie Claire Belgique\" \/>\n<meta property=\"og:description\" content=\"Envie de faire rimer f\u00eates de fin d&#039;ann\u00e9e avec sobri\u00e9t\u00e9 ? Voici une d\u00e9licieuse recette de dessert qui s&#039;accordera \u00e0 merveille avec votre mocktail pr\u00e9f\u00e9r\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/\" \/>\n<meta property=\"og:site_name\" content=\"Marie Claire Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarieClaire.Belgique\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-13T10:31:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2022\/12\/mocktail-dessert.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Malvine Sevrin\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Malvine Sevrin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\\\/\"},\"author\":{\"name\":\"Malvine Sevrin\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/#\\\/schema\\\/person\\\/c71bd7a8c3e622513c7531a39292a34e\"},\"headline\":\"Recettes : Mocktail Basilic &#038; Fleurs de sureau avec sabl\u00e9 breton et sorbet de cl\u00e9mentines\",\"datePublished\":\"2022-12-13T10:31:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\\\/\"},\"wordCount\":493,\"publisher\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/mocktail-dessert.png\",\"keywords\":[\"food\"],\"articleSection\":[\"Lifestyle\",\"Recettes\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\\\/\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\\\/\",\"name\":\"Recettes : Mocktail Basilic & Fleurs de sureau avec sabl\u00e9 breton et sorbet de cl\u00e9mentines - Marie Claire Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/mocktail-dessert.png\",\"datePublished\":\"2022-12-13T10:31:59+00:00\",\"description\":\"Envie de faire rimer f\u00eates de fin d'ann\u00e9e avec sobri\u00e9t\u00e9 ? Voici une d\u00e9licieuse recette de dessert qui s'accordera \u00e0 merveille avec votre mocktail pr\u00e9f\u00e9r\u00e9.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marieclaire.be\\\/fr\\\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/mocktail-dessert.png\",\"contentUrl\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/mocktail-dessert.png\",\"width\":1200,\"height\":628},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/\",\"name\":\"Marie Claire Belgique\",\"description\":\"Marie Claire Belgique, le magazine du style et de l\u2019intelligence qui parle de mode, des tendances, de la beaut\u00e9, de l\u2019actualit\u00e9 et de la culture\",\"publisher\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/#organization\",\"name\":\"Marie Claire\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/mc-logo2.png\",\"contentUrl\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/mc-logo2.png\",\"width\":1001,\"height\":189,\"caption\":\"Marie Claire\"},\"image\":{\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MarieClaire.Belgique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/marieclaire_belgique\\\/\",\"https:\\\/\\\/fr.pinterest.com\\\/marieclairebe\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BelgiumMarieClaire\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/#\\\/schema\\\/person\\\/c71bd7a8c3e622513c7531a39292a34e\",\"name\":\"Malvine Sevrin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/capture-decran-2024-02-13-a-145920-96x96.png\",\"url\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/capture-decran-2024-02-13-a-145920-96x96.png\",\"contentUrl\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/capture-decran-2024-02-13-a-145920-96x96.png\",\"caption\":\"Malvine Sevrin\"},\"description\":\"Des podiums parisiens aux derni\u00e8res nouveaut\u00e9s skincare qui enflamment TikTok, je d\u00e9crypte les tendances pour Marie Claire Belgique. Passionn\u00e9e de voyage, de mode et de beaut\u00e9, je partage mes coups de coeur d\u00e9nich\u00e9s aux quatre coins du globe. En tant que r\u00e9dactrice en chef digital, j'ai \u00e9galement \u00e0 coeur de mettre en lumi\u00e8re les histoires inspirantes de femmes \u00e0 travers notre site et sur nos r\u00e9seaux sociaux.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/malvinesev\\\/\"],\"url\":\"https:\\\/\\\/marieclaire.be\\\/fr\\\/author\\\/malvine\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recettes : Mocktail Basilic & Fleurs de sureau avec sabl\u00e9 breton et sorbet de cl\u00e9mentines - Marie Claire Belgique","description":"Envie de faire rimer f\u00eates de fin d'ann\u00e9e avec sobri\u00e9t\u00e9 ? Voici une d\u00e9licieuse recette de dessert qui s'accordera \u00e0 merveille avec votre mocktail pr\u00e9f\u00e9r\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/","next":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/2\/","og_locale":"fr_FR","og_type":"article","og_title":"Recettes : Mocktail Basilic & Fleurs de sureau avec sabl\u00e9 breton et sorbet de cl\u00e9mentines - Marie Claire Belgique","og_description":"Envie de faire rimer f\u00eates de fin d'ann\u00e9e avec sobri\u00e9t\u00e9 ? Voici une d\u00e9licieuse recette de dessert qui s'accordera \u00e0 merveille avec votre mocktail pr\u00e9f\u00e9r\u00e9.","og_url":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/","og_site_name":"Marie Claire Belgique","article_publisher":"https:\/\/www.facebook.com\/MarieClaire.Belgique\/","article_published_time":"2022-12-13T10:31:59+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2022\/12\/mocktail-dessert.png","type":"image\/png"}],"author":"Malvine Sevrin","twitter_misc":{"\u00c9crit par":"Malvine Sevrin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/#article","isPartOf":{"@id":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/"},"author":{"name":"Malvine Sevrin","@id":"https:\/\/marieclaire.be\/fr\/#\/schema\/person\/c71bd7a8c3e622513c7531a39292a34e"},"headline":"Recettes : Mocktail Basilic &#038; Fleurs de sureau avec sabl\u00e9 breton et sorbet de cl\u00e9mentines","datePublished":"2022-12-13T10:31:59+00:00","mainEntityOfPage":{"@id":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/"},"wordCount":493,"publisher":{"@id":"https:\/\/marieclaire.be\/fr\/#organization"},"image":{"@id":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/#primaryimage"},"thumbnailUrl":"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2022\/12\/mocktail-dessert.png","keywords":["food"],"articleSection":["Lifestyle","Recettes"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/","url":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/","name":"Recettes : Mocktail Basilic & Fleurs de sureau avec sabl\u00e9 breton et sorbet de cl\u00e9mentines - Marie Claire Belgique","isPartOf":{"@id":"https:\/\/marieclaire.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/#primaryimage"},"image":{"@id":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/#primaryimage"},"thumbnailUrl":"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2022\/12\/mocktail-dessert.png","datePublished":"2022-12-13T10:31:59+00:00","description":"Envie de faire rimer f\u00eates de fin d'ann\u00e9e avec sobri\u00e9t\u00e9 ? Voici une d\u00e9licieuse recette de dessert qui s'accordera \u00e0 merveille avec votre mocktail pr\u00e9f\u00e9r\u00e9.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/marieclaire.be\/fr\/recettes-mocktail-basilic-fleurs-de-sureau-avec-sable-breton-et-sorbet-de-clementines\/#primaryimage","url":"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2022\/12\/mocktail-dessert.png","contentUrl":"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2022\/12\/mocktail-dessert.png","width":1200,"height":628},{"@type":"WebSite","@id":"https:\/\/marieclaire.be\/fr\/#website","url":"https:\/\/marieclaire.be\/fr\/","name":"Marie Claire Belgique","description":"Marie Claire Belgique, le magazine du style et de l\u2019intelligence qui parle de mode, des tendances, de la beaut\u00e9, de l\u2019actualit\u00e9 et de la culture","publisher":{"@id":"https:\/\/marieclaire.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marieclaire.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/marieclaire.be\/fr\/#organization","name":"Marie Claire","url":"https:\/\/marieclaire.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/marieclaire.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2018\/05\/mc-logo2.png","contentUrl":"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2018\/05\/mc-logo2.png","width":1001,"height":189,"caption":"Marie Claire"},"image":{"@id":"https:\/\/marieclaire.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarieClaire.Belgique\/","https:\/\/www.instagram.com\/marieclaire_belgique\/","https:\/\/fr.pinterest.com\/marieclairebe\/","https:\/\/www.youtube.com\/user\/BelgiumMarieClaire"]},{"@type":"Person","@id":"https:\/\/marieclaire.be\/fr\/#\/schema\/person\/c71bd7a8c3e622513c7531a39292a34e","name":"Malvine Sevrin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2017\/05\/capture-decran-2024-02-13-a-145920-96x96.png","url":"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2017\/05\/capture-decran-2024-02-13-a-145920-96x96.png","contentUrl":"https:\/\/marieclaire.be\/fr\/wp-content\/uploads\/2017\/05\/capture-decran-2024-02-13-a-145920-96x96.png","caption":"Malvine Sevrin"},"description":"Des podiums parisiens aux derni\u00e8res nouveaut\u00e9s skincare qui enflamment TikTok, je d\u00e9crypte les tendances pour Marie Claire Belgique. Passionn\u00e9e de voyage, de mode et de beaut\u00e9, je partage mes coups de coeur d\u00e9nich\u00e9s aux quatre coins du globe. En tant que r\u00e9dactrice en chef digital, j'ai \u00e9galement \u00e0 coeur de mettre en lumi\u00e8re les histoires inspirantes de femmes \u00e0 travers notre site et sur nos r\u00e9seaux sociaux.","sameAs":["https:\/\/www.instagram.com\/malvinesev\/"],"url":"https:\/\/marieclaire.be\/fr\/author\/malvine\/"}]}},"_links":{"self":[{"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/posts\/121537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/comments?post=121537"}],"version-history":[{"count":2,"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/posts\/121537\/revisions"}],"predecessor-version":[{"id":121541,"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/posts\/121537\/revisions\/121541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/media\/121539"}],"wp:attachment":[{"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/media?parent=121537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/categories?post=121537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marieclaire.be\/fr\/wp-json\/wp\/v2\/tags?post=121537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}